{"id":4090,"date":"2024-08-10T22:07:39","date_gmt":"2024-08-10T22:07:39","guid":{"rendered":"https:\/\/bdgmatrix.com\/jobportal\/?post_type=candidate&#038;p=4090"},"modified":"2024-08-10T22:07:39","modified_gmt":"2024-08-10T22:07:39","slug":"adedoyin709","status":"publish","type":"candidate","link":"https:\/\/bdgmatrix.com\/jobportal\/candidate\/adedoyin709\/","title":{"rendered":"adedoyin709"},"content":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[],"candidate_location":[],"candidate_tag":[],"class_list":["post-4090","candidate","type-candidate","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/bdgmatrix.com\/jobportal\/candidate\/adedoyin709\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"BDG Matrix Job Portal - BDG Matrix Job Portal\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"adedoyin709 - BDG Matrix Job Portal\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/bdgmatrix.com\/jobportal\/candidate\/adedoyin709\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-08-10T22:07:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-08-10T22:07:39+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"adedoyin709 - BDG Matrix Job Portal\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/candidate\\\/adedoyin709\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/candidates\\\/#listItem\",\"name\":\"Candidates\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/candidates\\\/#listItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/candidates\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/candidate\\\/adedoyin709\\\/#listItem\",\"name\":\"adedoyin709\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/candidate\\\/adedoyin709\\\/#listItem\",\"position\":3,\"name\":\"adedoyin709\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/candidates\\\/#listItem\",\"name\":\"Candidates\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/#organization\",\"name\":\"BDG Matrix Jobs\",\"description\":\"BDG Matrix Job Portal\",\"url\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/candidate\\\/adedoyin709\\\/#webpage\",\"url\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/candidate\\\/adedoyin709\\\/\",\"name\":\"adedoyin709 - BDG Matrix Job Portal\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/candidate\\\/adedoyin709\\\/#breadcrumblist\"},\"datePublished\":\"2024-08-10T22:07:39+00:00\",\"dateModified\":\"2024-08-10T22:07:39+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/#website\",\"url\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/\",\"name\":\"BDG Matrix Jobs\",\"description\":\"BDG Matrix Job Portal\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/bdgmatrix.com\\\/jobportal\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"adedoyin709 - BDG Matrix Job Portal","description":"","canonical_url":"https:\/\/bdgmatrix.com\/jobportal\/candidate\/adedoyin709\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/bdgmatrix.com\/jobportal\/candidate\/adedoyin709\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/bdgmatrix.com\/jobportal#listItem","position":1,"name":"Home","item":"https:\/\/bdgmatrix.com\/jobportal","nextItem":{"@type":"ListItem","@id":"https:\/\/bdgmatrix.com\/jobportal\/candidates\/#listItem","name":"Candidates"}},{"@type":"ListItem","@id":"https:\/\/bdgmatrix.com\/jobportal\/candidates\/#listItem","position":2,"name":"Candidates","item":"https:\/\/bdgmatrix.com\/jobportal\/candidates\/","nextItem":{"@type":"ListItem","@id":"https:\/\/bdgmatrix.com\/jobportal\/candidate\/adedoyin709\/#listItem","name":"adedoyin709"},"previousItem":{"@type":"ListItem","@id":"https:\/\/bdgmatrix.com\/jobportal#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/bdgmatrix.com\/jobportal\/candidate\/adedoyin709\/#listItem","position":3,"name":"adedoyin709","previousItem":{"@type":"ListItem","@id":"https:\/\/bdgmatrix.com\/jobportal\/candidates\/#listItem","name":"Candidates"}}]},{"@type":"Organization","@id":"https:\/\/bdgmatrix.com\/jobportal\/#organization","name":"BDG Matrix Jobs","description":"BDG Matrix Job Portal","url":"https:\/\/bdgmatrix.com\/jobportal\/"},{"@type":"WebPage","@id":"https:\/\/bdgmatrix.com\/jobportal\/candidate\/adedoyin709\/#webpage","url":"https:\/\/bdgmatrix.com\/jobportal\/candidate\/adedoyin709\/","name":"adedoyin709 - BDG Matrix Job Portal","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/bdgmatrix.com\/jobportal\/#website"},"breadcrumb":{"@id":"https:\/\/bdgmatrix.com\/jobportal\/candidate\/adedoyin709\/#breadcrumblist"},"datePublished":"2024-08-10T22:07:39+00:00","dateModified":"2024-08-10T22:07:39+00:00"},{"@type":"WebSite","@id":"https:\/\/bdgmatrix.com\/jobportal\/#website","url":"https:\/\/bdgmatrix.com\/jobportal\/","name":"BDG Matrix Jobs","description":"BDG Matrix Job Portal","inLanguage":"en-US","publisher":{"@id":"https:\/\/bdgmatrix.com\/jobportal\/#organization"}}]},"og:locale":"en_US","og:site_name":"BDG Matrix Job Portal - BDG Matrix Job Portal","og:type":"article","og:title":"adedoyin709 - BDG Matrix Job Portal","og:url":"https:\/\/bdgmatrix.com\/jobportal\/candidate\/adedoyin709\/","article:published_time":"2024-08-10T22:07:39+00:00","article:modified_time":"2024-08-10T22:07:39+00:00","twitter:card":"summary_large_image","twitter:title":"adedoyin709 - BDG Matrix Job Portal"},"aioseo_meta_data":{"post_id":"4090","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-08-10 22:19:55","updated":"2025-06-04 16:20:55","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/bdgmatrix.com\/jobportal\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/bdgmatrix.com\/jobportal\/candidates\/\" title=\"Candidates\">Candidates<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tadedoyin709\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/bdgmatrix.com\/jobportal"},{"label":"Candidates","link":"https:\/\/bdgmatrix.com\/jobportal\/candidates\/"},{"label":"adedoyin709","link":"https:\/\/bdgmatrix.com\/jobportal\/candidate\/adedoyin709\/"}],"metas":{"_candidate_attached_user":"","_candidate_founded_date":"","_candidate_featured":"","_candidate_urgent":"","_candidate_expiry_date":"","_candidate_phone":"","_candidate_email":"adedoyin709@gmail.com","_candidate_gender":"","_candidate_age":"","_candidate_salary":"","_candidate_salary_type":"","_candidate_qualification":"","_candidate_experience_time":"","_candidate_category":[],"_candidate_languages":"","_candidate_job_title":"","_candidate_tag":[],"_candidate_show_profile":"show","_candidate_profile_url":"","_candidate_socials":"","_candidate_address":"","_candidate_location":[],"_candidate_map_location":{"address":"","latitude":"","longitude":""},"_candidate_cv_attachment":"","_candidate_portfolio_photos":"","_candidate_video_url":"","_candidate_education":"","_candidate_experience":"","_candidate_skill":""},"_links":{"self":[{"href":"https:\/\/bdgmatrix.com\/jobportal\/wp-json\/wp\/v2\/candidate\/4090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bdgmatrix.com\/jobportal\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/bdgmatrix.com\/jobportal\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/bdgmatrix.com\/jobportal\/wp-json\/wp\/v2\/comments?post=4090"}],"wp:attachment":[{"href":"https:\/\/bdgmatrix.com\/jobportal\/wp-json\/wp\/v2\/media?parent=4090"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/bdgmatrix.com\/jobportal\/wp-json\/wp\/v2\/candidate_category?post=4090"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/bdgmatrix.com\/jobportal\/wp-json\/wp\/v2\/candidate_location?post=4090"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/bdgmatrix.com\/jobportal\/wp-json\/wp\/v2\/candidate_tag?post=4090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}